{"id":461,"date":"2012-10-30T00:35:29","date_gmt":"2012-10-30T02:35:29","guid":{"rendered":"http:\/\/www.encontrabomretiro.com.br\/noticias\/?p=461"},"modified":"2019-04-29T18:04:40","modified_gmt":"2019-04-29T20:04:40","slug":"fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro","status":"publish","type":"post","link":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/","title":{"rendered":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro"},"content":{"rendered":"<div class=\"228b65ae207de3c5c501cfe75875708b\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Fernando Haddad (PT) foi eleito neste domingo prefeito da\u00a0cidade de S\u00e3o Paulo\u00a0com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital.<\/p>\n<p>O Encontra S\u00e3o Paulo\u00a0realizou um levantamento dos votos em todas as regi\u00f5es da cidade.<\/p>\n<p>Na regi\u00e3o do\u00a0bairro do Bom Retiro, que pertence ao col\u00e9gio eleitoral da Santa Efig\u00eania, o candidato do PT foi o mais votado.<\/p>\n<p>Veja como ficou a divis\u00e3o:<\/p>\n<p><strong>Jos\u00e9 Serra (PSDB)<\/strong>\u00a0\u2013 49,02%<\/p>\n<p><strong>Fernando Haddad (PT)<\/strong>\u00a0\u2013 50,98%<\/p>\n<p>Para conferir como ficou a vota\u00e7\u00e3o em todos os 58 col\u00e9gios eleitorais de S\u00e3o Paulo, acesse o link\u00a0http:\/\/eleicoes.folha.uol.com.br\/2012\/2turno\/mapa-sao_paulo.shtml.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Fernando Haddad (PT) foi eleito neste domingo prefeito da\u00a0cidade de S\u00e3o Paulo\u00a0com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo\u00a0realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o do\u00a0bairro do Bom Retiro, que pertence ao col\u00e9gio eleitoral da Santa Efig\u00eania, o candidato do PT foi o mais votado. Veja como ficou a divis\u00e3o: Jos\u00e9 Serra (PSDB)\u00a0\u2013 49,02% Fernando Haddad (PT)\u00a0\u2013 50,98% Para conferir como ficou a vota\u00e7\u00e3o em todos os 58 col\u00e9gios eleitorais <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14],"class_list":["post-461","post","type-post","status-publish","format-standard","hentry","category-noticias-no-bom-retiro","tag-bom-retiro"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Bom Retiro\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Bom Retiro | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas no bairro do Bom Retiro e regi\u00e3o.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro | Encontra Bom Retiro\" \/>\n\t\t<meta property=\"og:description\" content=\"Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-10-30T02:35:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T20:04:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro | Encontra Bom Retiro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#article\",\"name\":\"Fernando Haddad vence Jos\\u00e9 Serra na regi\\u00e3o do Bom Retiro | Encontra Bom Retiro\",\"headline\":\"Fernando Haddad vence Jos\\u00e9 Serra na regi\\u00e3o do Bom Retiro\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/author\\\/ebomretiro\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2012-10-30T00:35:29-02:00\",\"dateModified\":\"2019-04-29T18:04:40-02:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Bom Retiro, Bom Retiro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"Dom\\u00e9stica\",\"item\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/noticias-no-bom-retiro\\\/#listItem\",\"name\":\"Not\\u00edcias Bom Retiro\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/noticias-no-bom-retiro\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Bom Retiro\",\"item\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/noticias-no-bom-retiro\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#listItem\",\"name\":\"Fernando Haddad vence Jos\\u00e9 Serra na regi\\u00e3o do Bom Retiro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre#listItem\",\"name\":\"Dom\\u00e9stica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#listItem\",\"position\":3,\"name\":\"Fernando Haddad vence Jos\\u00e9 Serra na regi\\u00e3o do Bom Retiro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/noticias-no-bom-retiro\\\/#listItem\",\"name\":\"Not\\u00edcias Bom Retiro\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Bom Retiro\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas no bairro do Bom Retiro e regi\\u00e3o.\",\"url\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/author\\\/ebomretiro\\\/#author\",\"url\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/author\\\/ebomretiro\\\/\",\"name\":\"Encontra Bom Retiro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Bom Retiro\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/\",\"name\":\"Fernando Haddad vence Jos\\u00e9 Serra na regi\\u00e3o do Bom Retiro | Encontra Bom Retiro\",\"description\":\"Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\\u00e1lidos. J\\u00e1 Jos\\u00e9 Serra (PSDB) teve a prefer\\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\\u00e3o Paulo realizou um levantamento dos votos em todas as regi\\u00f5es da cidade. Na regi\\u00e3o\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/author\\\/ebomretiro\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/author\\\/ebomretiro\\\/#author\"},\"datePublished\":\"2012-10-30T00:35:29-02:00\",\"dateModified\":\"2019-04-29T18:04:40-02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/\",\"name\":\"Encontra Bom Retiro\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas no bairro do Bom Retiro e regi\\u00e3o.\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontrabomretiro.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro | Encontra Bom Retiro","description":"Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o","canonical_url":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#article","name":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro | Encontra Bom Retiro","headline":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro","author":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/author\/ebomretiro\/#author"},"publisher":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/#organization"},"datePublished":"2012-10-30T00:35:29-02:00","dateModified":"2019-04-29T18:04:40-02:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#webpage"},"articleSection":"Not\u00edcias Bom Retiro, Bom Retiro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre#listItem","position":1,"name":"Dom\u00e9stica","item":"https:\/\/www.encontrabomretiro.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/noticias-no-bom-retiro\/#listItem","name":"Not\u00edcias Bom Retiro"}},{"@type":"ListItem","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/noticias-no-bom-retiro\/#listItem","position":2,"name":"Not\u00edcias Bom Retiro","item":"https:\/\/www.encontrabomretiro.com.br\/sobre\/noticias-no-bom-retiro\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#listItem","name":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre#listItem","name":"Dom\u00e9stica"}},{"@type":"ListItem","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#listItem","position":3,"name":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/noticias-no-bom-retiro\/#listItem","name":"Not\u00edcias Bom Retiro"}}]},{"@type":"Organization","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/#organization","name":"Encontra Bom Retiro","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas no bairro do Bom Retiro e regi\u00e3o.","url":"https:\/\/www.encontrabomretiro.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/author\/ebomretiro\/#author","url":"https:\/\/www.encontrabomretiro.com.br\/sobre\/author\/ebomretiro\/","name":"Encontra Bom Retiro","image":{"@type":"ImageObject","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Bom Retiro"}},{"@type":"WebPage","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#webpage","url":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/","name":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro | Encontra Bom Retiro","description":"Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/author\/ebomretiro\/#author"},"creator":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/author\/ebomretiro\/#author"},"datePublished":"2012-10-30T00:35:29-02:00","dateModified":"2019-04-29T18:04:40-02:00"},{"@type":"WebSite","@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/#website","url":"https:\/\/www.encontrabomretiro.com.br\/sobre\/","name":"Encontra Bom Retiro","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas no bairro do Bom Retiro e regi\u00e3o.","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontrabomretiro.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Bom Retiro | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas no bairro do Bom Retiro e regi\u00e3o.","og:type":"article","og:title":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro | Encontra Bom Retiro","og:description":"Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o","og:url":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/","article:published_time":"2012-10-30T02:35:29+00:00","article:modified_time":"2019-04-29T20:04:40+00:00","twitter:card":"summary_large_image","twitter:title":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro | Encontra Bom Retiro","twitter:description":"Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o"},"aioseo_meta_data":{"post_id":"461","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-16 13:04:03","updated":"2025-10-03 14:03:38","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontrabomretiro.com.br\/sobre\" title=\"Dom\u00e9stica\">Dom\u00e9stica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontrabomretiro.com.br\/sobre\/noticias-no-bom-retiro\/\" title=\"Not\u00edcias Bom Retiro\">Not\u00edcias Bom Retiro<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Dom\u00e9stica","link":"https:\/\/www.encontrabomretiro.com.br\/sobre"},{"label":"Not\u00edcias Bom Retiro","link":"https:\/\/www.encontrabomretiro.com.br\/sobre\/noticias-no-bom-retiro\/"},{"label":"Fernando Haddad vence Jos\u00e9 Serra na regi\u00e3o do Bom Retiro","link":"https:\/\/www.encontrabomretiro.com.br\/sobre\/fernando-haddad-vence-jose-serra-na-regiao-do-bom-retiro\/"}],"_links":{"self":[{"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/posts\/461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=461"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/posts\/461\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabomretiro.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}